{"id":9357,"date":"2024-07-26T06:56:38","date_gmt":"2024-07-26T06:56:38","guid":{"rendered":"https:\/\/www.cevauto.com\/?p=9357"},"modified":"2024-07-26T07:13:11","modified_gmt":"2024-07-26T07:13:11","slug":"new-car-100-km-h-in-1-97-seconds-maximum-power-1548-horsepower-xiaomi-su7-ultra-prototype-official-picture","status":"publish","type":"post","link":"https:\/\/www.exp-byd.com\/es\/new-car-100-km-h-in-1-97-seconds-maximum-power-1548-horsepower-xiaomi-su7-ultra-prototype-official-picture\/","title":{"rendered":"Nuevo coche | 100 km\/h en 1,97 segundos\/potencia m\u00e1xima 1548 caballos, imagen oficial del prototipo Xiaomi SU7 Ultra"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"9357\" class=\"elementor elementor-9357\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5472402 e-flex e-con-boxed e-con e-parent\" data-id=\"5472402\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-06a25f3 elementor-widget elementor-widget-text-editor\" data-id=\"06a25f3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">El 19 de julio, en el \u201cDiscurso anual de Lei Jun 2024\u201d, se publicaron oficialmente las im\u00e1genes oficiales del prototipo Xiaomi SU7 Ultra.<\/span><\/span> <span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Se informa que el prototipo Xiaomi SU7 Ultra est\u00e1 equipado con dos motores V8 y un motor V6, con una potencia m\u00e1xima de 1548 caballos de fuerza y un tiempo de aceleraci\u00f3n de 0 a 100 kil\u00f3metros por hora de 1,97 segundos. El autom\u00f3vil desafiar\u00e1 la lista de tiempos de vuelta de producci\u00f3n no en masa de la pista &quot;N\u00fcrburgring&quot; en octubre de este a\u00f1o, y el autom\u00f3vil de producci\u00f3n en masa desafiar\u00e1 oficialmente la lista de tiempos de vuelta de producci\u00f3n en masa de la pista &quot;N\u00fcrburgring&quot; en 2025.<\/span><\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc150c3 elementor-widget elementor-widget-image\" data-id=\"fc150c3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1474\" height=\"1084\" src=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-2.webp\" class=\"attachment-full size-full wp-image-9379\" alt=\"\" srcset=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-2.webp 1474w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-2-300x221.webp 300w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-2-1024x753.webp 1024w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-2-768x565.webp 768w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-2-16x12.webp 16w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-2-1200x882.webp 1200w\" sizes=\"(max-width: 1474px) 100vw, 1474px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f00273f elementor-widget elementor-widget-image\" data-id=\"f00273f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1028\" height=\"762\" src=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-3.webp\" class=\"attachment-full size-full wp-image-9361\" alt=\"\" srcset=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-3.webp 1028w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-3-300x222.webp 300w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-3-1024x759.webp 1024w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-3-768x569.webp 768w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-3-16x12.webp 16w\" sizes=\"(max-width: 1028px) 100vw, 1028px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15d8b25 elementor-widget elementor-widget-image\" data-id=\"15d8b25\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1054\" height=\"774\" src=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-4.webp\" class=\"attachment-full size-full wp-image-9362\" alt=\"\" srcset=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-4.webp 1054w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-4-300x220.webp 300w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-4-1024x752.webp 1024w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-4-768x564.webp 768w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-4-16x12.webp 16w\" sizes=\"(max-width: 1054px) 100vw, 1054px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-602bb87 elementor-widget elementor-widget-text-editor\" data-id=\"602bb87\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">El prototipo Xiaomi SU7 Ultra est\u00e1 equipado con una gran cantidad de kits deportivos para la carrocer\u00eda, que incluyen un gran aler\u00f3n, borde frontal, faldones laterales y difusor trasero, que muestran una mayor sensaci\u00f3n de deportividad en su conjunto.<\/span><\/span> <span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">En t\u00e9rminos de dimensiones de la carrocer\u00eda, la longitud, la anchura y la altura del coche son 5260\/2064\/1406 mm respectivamente, y la distancia entre ejes es de 3000 mm.<\/span><\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae0565d elementor-widget elementor-widget-image\" data-id=\"ae0565d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1500\" height=\"1120\" src=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-5.webp\" class=\"attachment-full size-full wp-image-9363\" alt=\"\" srcset=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-5.webp 1500w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-5-300x224.webp 300w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-5-1024x765.webp 1024w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-5-768x573.webp 768w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-5-16x12.webp 16w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-5-1200x896.webp 1200w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bbf1d0e elementor-widget elementor-widget-image\" data-id=\"bbf1d0e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1424\" height=\"1110\" src=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-6.webp\" class=\"attachment-full size-full wp-image-9374\" alt=\"\" srcset=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-6.webp 1424w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-6-300x234.webp 300w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-6-1024x798.webp 1024w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-6-768x599.webp 768w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-6-15x12.webp 15w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-6-1200x935.webp 1200w\" sizes=\"(max-width: 1424px) 100vw, 1424px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d4fe00 elementor-widget elementor-widget-image\" data-id=\"5d4fe00\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1212\" height=\"882\" src=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-7.webp\" class=\"attachment-full size-full wp-image-9373\" alt=\"\" srcset=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-7.webp 1212w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-7-300x218.webp 300w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-7-1024x745.webp 1024w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-7-768x559.webp 768w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-7-16x12.webp 16w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-7-1200x873.webp 1200w\" sizes=\"(max-width: 1212px) 100vw, 1212px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-095d585 elementor-widget elementor-widget-image\" data-id=\"095d585\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1440\" height=\"1920\" src=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-8.webp\" class=\"attachment-full size-full wp-image-9372\" alt=\"\" srcset=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-8.webp 1440w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-8-225x300.webp 225w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-8-768x1024.webp 768w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-8-1152x1536.webp 1152w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-8-9x12.webp 9w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-8-1200x1600.webp 1200w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f3d40f elementor-widget elementor-widget-image\" data-id=\"7f3d40f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1436\" height=\"660\" src=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-9.webp\" class=\"attachment-full size-full wp-image-9371\" alt=\"\" srcset=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-9.webp 1436w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-9-300x138.webp 300w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-9-1024x471.webp 1024w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-9-768x353.webp 768w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-9-18x8.webp 18w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-9-1200x552.webp 1200w\" sizes=\"(max-width: 1436px) 100vw, 1436px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce094a5 elementor-widget elementor-widget-image\" data-id=\"ce094a5\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1100\" height=\"572\" src=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-10.webp\" class=\"attachment-full size-full wp-image-9370\" alt=\"\" srcset=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-10.webp 1100w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-10-300x156.webp 300w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-10-1024x532.webp 1024w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-10-768x399.webp 768w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-10-18x9.webp 18w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-376fbc5 elementor-widget elementor-widget-image\" data-id=\"376fbc5\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1106\" height=\"706\" src=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-11.webp\" class=\"attachment-full size-full wp-image-9369\" alt=\"\" srcset=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-11.webp 1106w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-11-300x192.webp 300w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-11-1024x654.webp 1024w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-11-768x490.webp 768w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-11-18x12.webp 18w\" sizes=\"(max-width: 1106px) 100vw, 1106px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-803f620 elementor-widget elementor-widget-image\" data-id=\"803f620\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1162\" height=\"632\" src=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-12.webp\" class=\"attachment-full size-full wp-image-9368\" alt=\"\" srcset=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-12.webp 1162w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-12-300x163.webp 300w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-12-1024x557.webp 1024w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-12-768x418.webp 768w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-12-18x10.webp 18w\" sizes=\"(max-width: 1162px) 100vw, 1162px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b4693f8 elementor-widget elementor-widget-image\" data-id=\"b4693f8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1050\" height=\"1392\" src=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-13.webp\" class=\"attachment-full size-full wp-image-9367\" alt=\"\" srcset=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-13.webp 1050w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-13-226x300.webp 226w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-13-772x1024.webp 772w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-13-768x1018.webp 768w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-13-9x12.webp 9w\" sizes=\"(max-width: 1050px) 100vw, 1050px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c34fb67 elementor-widget elementor-widget-image\" data-id=\"c34fb67\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1042\" height=\"1418\" src=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-14.webp\" class=\"attachment-full size-full wp-image-9366\" alt=\"\" srcset=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-14.webp 1042w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-14-220x300.webp 220w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-14-752x1024.webp 752w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-14-768x1045.webp 768w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-14-9x12.webp 9w\" sizes=\"(max-width: 1042px) 100vw, 1042px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a34b55a elementor-widget elementor-widget-image\" data-id=\"a34b55a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1048\" height=\"1392\" src=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-15.webp\" class=\"attachment-full size-full wp-image-9365\" alt=\"\" srcset=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-15.webp 1048w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-15-226x300.webp 226w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-15-771x1024.webp 771w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-15-768x1020.webp 768w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-15-9x12.webp 9w\" sizes=\"(max-width: 1048px) 100vw, 1048px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1134d4 elementor-widget elementor-widget-image\" data-id=\"b1134d4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1056\" height=\"1396\" src=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-16.webp\" class=\"attachment-full size-full wp-image-9364\" alt=\"\" srcset=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-16.webp 1056w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-16-227x300.webp 227w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-16-775x1024.webp 775w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-16-768x1015.webp 768w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/07\/20240726-16-9x12.webp 9w\" sizes=\"(max-width: 1056px) 100vw, 1056px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-81329b4 elementor-widget elementor-widget-text-editor\" data-id=\"81329b4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">En t\u00e9rminos de potencia, el prototipo Xiaomi SU7 Ultra est\u00e1 equipado con dos motores V8 y un motor V6, con una potencia m\u00e1xima de 1.548 caballos, un tiempo de aceleraci\u00f3n de 0 a 100 km\/h de 1,97 segundos y una velocidad m\u00e1xima de m\u00e1s de 350 km\/h.<\/span><\/span> <span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Adem\u00e1s, el coche est\u00e1 equipado con un paquete de bater\u00edas de alta potencia especialmente dise\u00f1ado para la pista de CATL Kirin II.<\/span><\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77207cf elementor-widget elementor-widget-text-editor\" data-id=\"77207cf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Se informa que el motor V8 adopta un dise\u00f1o de circuito de aceite tridimensional en forma de S y refrigeraci\u00f3n de aceite completa de dos v\u00edas. La parte del estator utiliza un circuito de aceite tridimensional de doble circulaci\u00f3n para aumentar a\u00fan m\u00e1s el \u00e1rea de disipaci\u00f3n de calor; la parte del rotor utiliza un circuito de aceite en forma de S para aumentar el \u00e1rea de disipaci\u00f3n de calor simult\u00e1neamente.<\/span><\/span> <span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Adem\u00e1s, las laminaciones de acero al silicio del estator tambi\u00e9n adoptan un dise\u00f1o escalonado de \u201ctipo escalonado\u201d, que puede aumentar el \u00e1rea de disipaci\u00f3n de calor efectiva en 7%.<\/span><\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-87970f5 elementor-widget elementor-widget-text-editor\" data-id=\"87970f5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Como referencia, el Xiaomi SU7 actualmente a la venta ofrece modelos con un solo motor y con dos motores. La versi\u00f3n con un solo motor (SU7 y SU7 Pro) tiene una potencia m\u00e1xima de 200 kW y un par m\u00e1ximo de 400 Nm para el motor trasero, y proporciona 73,6 kWh y 94,3 kWh de bater\u00edas de fosfato de hierro y litio, con autonom\u00edas el\u00e9ctricas puras CLTC correspondientes de 700 km y 830 km respectivamente; la versi\u00f3n con dos motores (SU7 Max) tiene una potencia total del motor de 495 kW y un par m\u00e1ximo de 838 Nm, combinado con una bater\u00eda ternaria de litio con una capacidad de 101 kWh, y una autonom\u00eda el\u00e9ctrica pura CLTC de 800 km.<\/span><\/span><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\"> Se informa que la funci\u00f3n de defensa de activaci\u00f3n externa del Xiaomi SU7 se lanzar\u00e1 pronto, y est\u00e1 previsto que toda la serie Xiaomi SU7 se implemente a trav\u00e9s de actualizaciones OTA en agosto de 2024.<\/span><\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b7d6fe8 elementor-widget elementor-widget-text-editor\" data-id=\"b7d6fe8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>En t\u00e9rminos de rendimiento, el tiempo de aceleraci\u00f3n del Xiaomi SU7 de 0 a 100 km\/h es de 5,28 segundos; el tiempo de aceleraci\u00f3n del Xiaomi SU7 Pro de 0 a 100 km\/h es de 5,7 segundos; el tiempo de aceleraci\u00f3n del Xiaomi SU7 Max de 0 a 100 km\/h es de 2,78 segundos.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>El 19 de julio, en el \u201cDiscurso anual de Lei Jun 2024\u201d, se publicaron oficialmente las im\u00e1genes oficiales del prototipo Xiaomi SU7 Ultra. Se informa que el prototipo Xiaomi SU7 Ultra est\u00e1 equipado con dos motores V8 y un motor V6, con una potencia m\u00e1xima de 1548 caballos de fuerza y un tiempo de aceleraci\u00f3n de 0 a 100 kil\u00f3metros [\u2026]<\/p>","protected":false},"author":1,"featured_media":9360,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rank_math_lock_modified_date":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-9357","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-industry-news"],"_links":{"self":[{"href":"https:\/\/www.exp-byd.com\/es\/wp-json\/wp\/v2\/posts\/9357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.exp-byd.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.exp-byd.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.exp-byd.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.exp-byd.com\/es\/wp-json\/wp\/v2\/comments?post=9357"}],"version-history":[{"count":7,"href":"https:\/\/www.exp-byd.com\/es\/wp-json\/wp\/v2\/posts\/9357\/revisions"}],"predecessor-version":[{"id":9382,"href":"https:\/\/www.exp-byd.com\/es\/wp-json\/wp\/v2\/posts\/9357\/revisions\/9382"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.exp-byd.com\/es\/wp-json\/wp\/v2\/media\/9360"}],"wp:attachment":[{"href":"https:\/\/www.exp-byd.com\/es\/wp-json\/wp\/v2\/media?parent=9357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.exp-byd.com\/es\/wp-json\/wp\/v2\/categories?post=9357"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.exp-byd.com\/es\/wp-json\/wp\/v2\/tags?post=9357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}