{"id":10319,"date":"2024-09-09T02:15:38","date_gmt":"2024-09-09T02:15:38","guid":{"rendered":"https:\/\/www.cevauto.com\/?p=10319"},"modified":"2024-09-09T02:44:42","modified_gmt":"2024-09-09T02:44:42","slug":"the-new-mengshi-m800-is-launched","status":"publish","type":"post","link":"https:\/\/www.exp-byd.com\/fr\/the-new-mengshi-m800-is-launched\/","title":{"rendered":"Lancement du nouveau M-hero M800"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"10319\" class=\"elementor elementor-10319\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cd10713 e-flex e-con-boxed e-con e-parent\" data-id=\"cd10713\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d1db3ff elementor-widget elementor-widget-image\" data-id=\"d1db3ff\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2508\" height=\"1672\" src=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/c8ddf2915ae64ab9a458ae00b1297cb1noop.webp\" class=\"attachment-full size-full wp-image-10338\" alt=\"\" srcset=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/c8ddf2915ae64ab9a458ae00b1297cb1noop.webp 2508w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/c8ddf2915ae64ab9a458ae00b1297cb1noop-300x200.webp 300w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/c8ddf2915ae64ab9a458ae00b1297cb1noop-1024x683.webp 1024w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/c8ddf2915ae64ab9a458ae00b1297cb1noop-768x512.webp 768w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/c8ddf2915ae64ab9a458ae00b1297cb1noop-1536x1024.webp 1536w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/c8ddf2915ae64ab9a458ae00b1297cb1noop-2048x1365.webp 2048w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/c8ddf2915ae64ab9a458ae00b1297cb1noop-18x12.webp 18w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/c8ddf2915ae64ab9a458ae00b1297cb1noop-1200x800.webp 1200w\" sizes=\"(max-width: 2508px) 100vw, 2508px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e540c2 elementor-widget elementor-widget-image\" data-id=\"3e540c2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2508\" height=\"1672\" src=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/6873035b80524cf29f6a6300ff4b05a3noop.webp\" class=\"attachment-full size-full wp-image-10337\" alt=\"\" srcset=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/6873035b80524cf29f6a6300ff4b05a3noop.webp 2508w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/6873035b80524cf29f6a6300ff4b05a3noop-300x200.webp 300w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/6873035b80524cf29f6a6300ff4b05a3noop-1024x683.webp 1024w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/6873035b80524cf29f6a6300ff4b05a3noop-768x512.webp 768w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/6873035b80524cf29f6a6300ff4b05a3noop-1536x1024.webp 1536w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/6873035b80524cf29f6a6300ff4b05a3noop-2048x1365.webp 2048w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/6873035b80524cf29f6a6300ff4b05a3noop-18x12.webp 18w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/6873035b80524cf29f6a6300ff4b05a3noop-1200x800.webp 1200w\" sizes=\"(max-width: 2508px) 100vw, 2508px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c4db82 elementor-widget elementor-widget-text-editor\" data-id=\"9c4db82\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>En termes d&#039;apparence, la M800 a une ligne de carrosserie de style \u00ab mecha \u00bb, et les feux avant et arri\u00e8re ainsi que l&#039;entourage avant sont tr\u00e8s reconnaissables. En tant que mod\u00e8le personnalis\u00e9 haut de gamme, la M800 est livr\u00e9e de s\u00e9rie avec un entourage de char \u00e9toil\u00e9, un capot en fibre de carbone, une plaque signal\u00e9tique exclusive, un toit sur\u00e9lev\u00e9 en fibre de carbone et un sac \u00e0 dos en fibre de carbone.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d61c0de elementor-widget elementor-widget-image\" data-id=\"d61c0de\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2508\" height=\"1672\" src=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/35e246cfb02d4e45ada56ad4067a236bnoop.webp\" class=\"attachment-full size-full wp-image-10336\" alt=\"\" srcset=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/35e246cfb02d4e45ada56ad4067a236bnoop.webp 2508w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/35e246cfb02d4e45ada56ad4067a236bnoop-300x200.webp 300w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/35e246cfb02d4e45ada56ad4067a236bnoop-1024x683.webp 1024w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/35e246cfb02d4e45ada56ad4067a236bnoop-768x512.webp 768w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/35e246cfb02d4e45ada56ad4067a236bnoop-1536x1024.webp 1536w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/35e246cfb02d4e45ada56ad4067a236bnoop-2048x1365.webp 2048w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/35e246cfb02d4e45ada56ad4067a236bnoop-18x12.webp 18w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/35e246cfb02d4e45ada56ad4067a236bnoop-1200x800.webp 1200w\" sizes=\"(max-width: 2508px) 100vw, 2508px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a95966 elementor-widget elementor-widget-image\" data-id=\"1a95966\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2508\" height=\"1672\" src=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/72310d86a564405391b467bf74eff4f2noop.webp\" class=\"attachment-full size-full wp-image-10335\" alt=\"\" srcset=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/72310d86a564405391b467bf74eff4f2noop.webp 2508w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/72310d86a564405391b467bf74eff4f2noop-300x200.webp 300w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/72310d86a564405391b467bf74eff4f2noop-1024x683.webp 1024w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/72310d86a564405391b467bf74eff4f2noop-768x512.webp 768w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/72310d86a564405391b467bf74eff4f2noop-1536x1024.webp 1536w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/72310d86a564405391b467bf74eff4f2noop-2048x1365.webp 2048w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/72310d86a564405391b467bf74eff4f2noop-18x12.webp 18w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/72310d86a564405391b467bf74eff4f2noop-1200x800.webp 1200w\" sizes=\"(max-width: 2508px) 100vw, 2508px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-594495c elementor-widget elementor-widget-image\" data-id=\"594495c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2508\" height=\"1672\" src=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/8390acdc2bdb46679b6bebde951cbff7noop.webp\" class=\"attachment-full size-full wp-image-10334\" alt=\"\" srcset=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/8390acdc2bdb46679b6bebde951cbff7noop.webp 2508w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/8390acdc2bdb46679b6bebde951cbff7noop-300x200.webp 300w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/8390acdc2bdb46679b6bebde951cbff7noop-1024x683.webp 1024w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/8390acdc2bdb46679b6bebde951cbff7noop-768x512.webp 768w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/8390acdc2bdb46679b6bebde951cbff7noop-1536x1024.webp 1536w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/8390acdc2bdb46679b6bebde951cbff7noop-2048x1365.webp 2048w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/8390acdc2bdb46679b6bebde951cbff7noop-18x12.webp 18w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/8390acdc2bdb46679b6bebde951cbff7noop-1200x800.webp 1200w\" sizes=\"(max-width: 2508px) 100vw, 2508px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43d8cf0 elementor-widget elementor-widget-text-editor\" data-id=\"43d8cf0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"AxqVh\"><div class=\"OPPzxe\"><div class=\"QcsUad BDJ8fb BLojaf sMVRZe hCXDsb wneUed\"><div class=\"usGWQd\"><div class=\"KkbLmb\"><div class=\"lRu31\" dir=\"ltr\"><span class=\"HwtZe\" lang=\"en\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">En termes de taille de carrosserie, la longueur, la largeur et la hauteur de la M800 sont respectivement de 5136\/2172\/2063 mm, et l&#039;empattement est de 2950 mm. \u00c0 titre de r\u00e9f\u00e9rence, la longueur, la largeur et la hauteur de la 917 sont respectivement de 4987\/2080\/1935 mm, et l&#039;empattement est de 2950 mm. En comparaison, la longueur, la largeur et la hauteur de la M800 sont plus grandes que celles de la 917.<\/span><\/span><\/span><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-34c685c elementor-widget elementor-widget-image\" data-id=\"34c685c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2508\" height=\"1672\" src=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/48e91592b9bf46f8a7eee38153047612noop.webp\" class=\"attachment-full size-full wp-image-10333\" alt=\"\" srcset=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/48e91592b9bf46f8a7eee38153047612noop.webp 2508w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/48e91592b9bf46f8a7eee38153047612noop-300x200.webp 300w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/48e91592b9bf46f8a7eee38153047612noop-1024x683.webp 1024w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/48e91592b9bf46f8a7eee38153047612noop-768x512.webp 768w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/48e91592b9bf46f8a7eee38153047612noop-1536x1024.webp 1536w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/48e91592b9bf46f8a7eee38153047612noop-2048x1365.webp 2048w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/48e91592b9bf46f8a7eee38153047612noop-18x12.webp 18w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/48e91592b9bf46f8a7eee38153047612noop-1200x800.webp 1200w\" sizes=\"(max-width: 2508px) 100vw, 2508px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8858e37 elementor-widget elementor-widget-image\" data-id=\"8858e37\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2508\" height=\"1672\" src=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/c2e78c2ec5904000bb866eef478bfb1bnoop.webp\" class=\"attachment-full size-full wp-image-10332\" alt=\"\" srcset=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/c2e78c2ec5904000bb866eef478bfb1bnoop.webp 2508w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/c2e78c2ec5904000bb866eef478bfb1bnoop-300x200.webp 300w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/c2e78c2ec5904000bb866eef478bfb1bnoop-1024x683.webp 1024w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/c2e78c2ec5904000bb866eef478bfb1bnoop-768x512.webp 768w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/c2e78c2ec5904000bb866eef478bfb1bnoop-1536x1024.webp 1536w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/c2e78c2ec5904000bb866eef478bfb1bnoop-2048x1365.webp 2048w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/c2e78c2ec5904000bb866eef478bfb1bnoop-18x12.webp 18w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/c2e78c2ec5904000bb866eef478bfb1bnoop-1200x800.webp 1200w\" sizes=\"(max-width: 2508px) 100vw, 2508px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5de6052 elementor-widget elementor-widget-image\" data-id=\"5de6052\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2508\" height=\"1672\" src=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/2b596d9474f24e4aafbc9702d89fbe60noop.webp\" class=\"attachment-full size-full wp-image-10331\" alt=\"\" srcset=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/2b596d9474f24e4aafbc9702d89fbe60noop.webp 2508w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/2b596d9474f24e4aafbc9702d89fbe60noop-300x200.webp 300w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/2b596d9474f24e4aafbc9702d89fbe60noop-1024x683.webp 1024w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/2b596d9474f24e4aafbc9702d89fbe60noop-768x512.webp 768w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/2b596d9474f24e4aafbc9702d89fbe60noop-1536x1024.webp 1536w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/2b596d9474f24e4aafbc9702d89fbe60noop-2048x1365.webp 2048w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/2b596d9474f24e4aafbc9702d89fbe60noop-18x12.webp 18w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/2b596d9474f24e4aafbc9702d89fbe60noop-1200x800.webp 1200w\" sizes=\"(max-width: 2508px) 100vw, 2508px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-09e3ead elementor-widget elementor-widget-text-editor\" data-id=\"09e3ead\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>En termes d&#039;int\u00e9rieur, la M800 continue fondamentalement la disposition de la 917, \u00e9quip\u00e9e d&#039;un tableau de bord flottant, d&#039;un \u00e9cran de contr\u00f4le central, d&#039;un \u00e9cran de copilote, etc. Cependant, la nouvelle voiture utilise les couleurs int\u00e9rieures Obsidian Black, Interstellar Gray et Hermes Orange\/Morandi Green, et ajoute des panneaux d\u00e9coratifs en fibre de carbone \u00e0 la console centrale, aux poign\u00e9es de porte et \u00e0 la zone du levier de vitesses.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2179da1 elementor-widget elementor-widget-image\" data-id=\"2179da1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2508\" height=\"1672\" src=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/53178a63acfd48b28b4e64c3c3ad64bbnoop.webp\" class=\"attachment-full size-full wp-image-10330\" alt=\"\" srcset=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/53178a63acfd48b28b4e64c3c3ad64bbnoop.webp 2508w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/53178a63acfd48b28b4e64c3c3ad64bbnoop-300x200.webp 300w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/53178a63acfd48b28b4e64c3c3ad64bbnoop-1024x683.webp 1024w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/53178a63acfd48b28b4e64c3c3ad64bbnoop-768x512.webp 768w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/53178a63acfd48b28b4e64c3c3ad64bbnoop-1536x1024.webp 1536w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/53178a63acfd48b28b4e64c3c3ad64bbnoop-2048x1365.webp 2048w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/53178a63acfd48b28b4e64c3c3ad64bbnoop-18x12.webp 18w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/53178a63acfd48b28b4e64c3c3ad64bbnoop-1200x800.webp 1200w\" sizes=\"(max-width: 2508px) 100vw, 2508px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ec25f9 elementor-widget elementor-widget-text-editor\" data-id=\"8ec25f9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>En termes d&#039;int\u00e9rieur, la M800 continue fondamentalement la disposition de la 917, \u00e9quip\u00e9e d&#039;un tableau de bord flottant, d&#039;un \u00e9cran de contr\u00f4le central, d&#039;un \u00e9cran de copilote, etc. Cependant, la nouvelle voiture utilise les couleurs int\u00e9rieures Obsidian Black, Interstellar Gray et Hermes Orange\/Morandi Green, et ajoute des panneaux d\u00e9coratifs en fibre de carbone \u00e0 la console centrale, aux poign\u00e9es de porte et \u00e0 la zone du levier de vitesses.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-084c84e elementor-widget elementor-widget-image\" data-id=\"084c84e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2508\" height=\"1672\" src=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/9d2a4b055c96420ba67771de7d26db14noop.webp\" class=\"attachment-full size-full wp-image-10329\" alt=\"\" srcset=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/9d2a4b055c96420ba67771de7d26db14noop.webp 2508w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/9d2a4b055c96420ba67771de7d26db14noop-300x200.webp 300w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/9d2a4b055c96420ba67771de7d26db14noop-1024x683.webp 1024w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/9d2a4b055c96420ba67771de7d26db14noop-768x512.webp 768w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/9d2a4b055c96420ba67771de7d26db14noop-1536x1024.webp 1536w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/9d2a4b055c96420ba67771de7d26db14noop-2048x1365.webp 2048w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/9d2a4b055c96420ba67771de7d26db14noop-18x12.webp 18w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/9d2a4b055c96420ba67771de7d26db14noop-1200x800.webp 1200w\" sizes=\"(max-width: 2508px) 100vw, 2508px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8471389 elementor-widget elementor-widget-image\" data-id=\"8471389\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2508\" height=\"1672\" src=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/b78d8025a6724019bbb394b80f59e07dnoop.webp\" class=\"attachment-full size-full wp-image-10327\" alt=\"\" srcset=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/b78d8025a6724019bbb394b80f59e07dnoop.webp 2508w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/b78d8025a6724019bbb394b80f59e07dnoop-300x200.webp 300w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/b78d8025a6724019bbb394b80f59e07dnoop-1024x683.webp 1024w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/b78d8025a6724019bbb394b80f59e07dnoop-768x512.webp 768w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/b78d8025a6724019bbb394b80f59e07dnoop-1536x1024.webp 1536w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/b78d8025a6724019bbb394b80f59e07dnoop-2048x1365.webp 2048w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/b78d8025a6724019bbb394b80f59e07dnoop-18x12.webp 18w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/b78d8025a6724019bbb394b80f59e07dnoop-1200x800.webp 1200w\" sizes=\"(max-width: 2508px) 100vw, 2508px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4bda220 elementor-widget elementor-widget-image\" data-id=\"4bda220\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2508\" height=\"1672\" src=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/c5b394ce730b4431817729e6ca4fdaf7noop.webp\" class=\"attachment-full size-full wp-image-10326\" alt=\"\" srcset=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/c5b394ce730b4431817729e6ca4fdaf7noop.webp 2508w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/c5b394ce730b4431817729e6ca4fdaf7noop-300x200.webp 300w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/c5b394ce730b4431817729e6ca4fdaf7noop-1024x683.webp 1024w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/c5b394ce730b4431817729e6ca4fdaf7noop-768x512.webp 768w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/c5b394ce730b4431817729e6ca4fdaf7noop-1536x1024.webp 1536w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/c5b394ce730b4431817729e6ca4fdaf7noop-2048x1365.webp 2048w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/c5b394ce730b4431817729e6ca4fdaf7noop-18x12.webp 18w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/09\/c5b394ce730b4431817729e6ca4fdaf7noop-1200x800.webp 1200w\" sizes=\"(max-width: 2508px) 100vw, 2508px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29679f7 elementor-widget elementor-widget-text-editor\" data-id=\"29679f7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>La M800 est \u00e9galement \u00e9quip\u00e9e d&#039;une petite table pour le conducteur et le copilote, de patins antid\u00e9rapants pour les dossiers du coffre\/des si\u00e8ges arri\u00e8re, etc. Il est rapport\u00e9 que le volume du coffre de la voiture est de 420 litres et permet de rabattre les si\u00e8ges arri\u00e8re.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3889cd1 elementor-widget elementor-widget-text-editor\" data-id=\"3889cd1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"lRu31\" dir=\"ltr\"><span class=\"HwtZe\" lang=\"en\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">En termes de configuration, la M800 est \u00e9quip\u00e9e du syst\u00e8me tout-terrain Mengshi, du syst\u00e8me de contr\u00f4le dynamique VMC, du syst\u00e8me de capteur de passage \u00e0 gu\u00e9, du syst\u00e8me de s\u00e9curit\u00e9 de stationnement, du mode tout-terrain, du mode crabe, du mode rampant, du ch\u00e2ssis transparent, des blocages de diff\u00e9rentiel \u00e9lectroniques avant et arri\u00e8re, des crochets de remorque avant et arri\u00e8re, etc. En outre, la voiture est \u00e9galement \u00e9quip\u00e9e de phares antibrouillard avant \u00e0 LED (avec assistance de direction), d&#039;un kit de plate-forme de toit d&#039;origine, d&#039;un coffre de rangement externe arri\u00e8re et de pneus tout-terrain de 20 pouces. En termes de param\u00e8tres li\u00e9s au tout-terrain, la nouvelle voiture a une plage de r\u00e9glage de la hauteur de carrosserie de 150 mm, une garde au sol minimale de 221 mm \u00e0 326 mm, un angle de franchissement de 22,6 degr\u00e9s, un angle de braquage des roues arri\u00e8re de 10,27 degr\u00e9s, un rayon de braquage minimum de 5,1 m\u00e8tres et une profondeur de gu\u00e9 maximale de 850 mm.<\/span><\/span><\/span><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-678057b elementor-widget elementor-widget-text-editor\" data-id=\"678057b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>En termes de puissance, la M800 est \u00e9quip\u00e9e d&#039;un syst\u00e8me hybride \u00e0 autonomie prolong\u00e9e compos\u00e9 d&#039;un prolongateur d&#039;autonomie 1,5T et d&#039;un moteur \u00e9lectrique. La puissance maximale du prolongateur d&#039;autonomie 1,5T est de 145 kilowatts, ce qui est conforme \u00e0 celle de la 917. La puissance maximale du moteur \u00e9lectrique est de 600 kilowatts, le couple maximal global du syst\u00e8me est de 1050 Nm, associ\u00e9 \u00e0 une batterie lithium ternaire d&#039;une capacit\u00e9 de 65,8 kWh, et l&#039;autonomie \u00e9lectrique pure CLTC est de 125 kilom\u00e8tres.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>En termes d&#039;apparence, la M800 a une ligne de carrosserie de style \u00ab mecha \u00bb, et les feux avant et arri\u00e8re ainsi que l&#039;entourage avant sont tr\u00e8s reconnaissables. En tant que mod\u00e8le personnalis\u00e9 haut de gamme, la M800 est livr\u00e9e de s\u00e9rie avec un entourage de char \u00e9toil\u00e9, un capot en fibre de carbone, une plaque signal\u00e9tique exclusive, un toit sur\u00e9lev\u00e9 en fibre de carbone et un sac \u00e0 dos en fibre de carbone. [\u2026]<\/p>","protected":false},"author":1,"featured_media":10339,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rank_math_lock_modified_date":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-10319","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-industry-news"],"_links":{"self":[{"href":"https:\/\/www.exp-byd.com\/fr\/wp-json\/wp\/v2\/posts\/10319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.exp-byd.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.exp-byd.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.exp-byd.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.exp-byd.com\/fr\/wp-json\/wp\/v2\/comments?post=10319"}],"version-history":[{"count":8,"href":"https:\/\/www.exp-byd.com\/fr\/wp-json\/wp\/v2\/posts\/10319\/revisions"}],"predecessor-version":[{"id":10342,"href":"https:\/\/www.exp-byd.com\/fr\/wp-json\/wp\/v2\/posts\/10319\/revisions\/10342"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.exp-byd.com\/fr\/wp-json\/wp\/v2\/media\/10339"}],"wp:attachment":[{"href":"https:\/\/www.exp-byd.com\/fr\/wp-json\/wp\/v2\/media?parent=10319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.exp-byd.com\/fr\/wp-json\/wp\/v2\/categories?post=10319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.exp-byd.com\/fr\/wp-json\/wp\/v2\/tags?post=10319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}