{"id":10523,"date":"2024-10-10T01:13:54","date_gmt":"2024-10-10T01:13:54","guid":{"rendered":"https:\/\/www.cevauto.com\/?p=10523"},"modified":"2024-10-10T01:39:11","modified_gmt":"2024-10-10T01:39:11","slug":"new-car-geely-xingyuan-officially-launched","status":"publish","type":"post","link":"https:\/\/www.exp-byd.com\/pt\/new-car-geely-xingyuan-officially-launched\/","title":{"rendered":"Novo carro | Geely Xingyuan lan\u00e7ado oficialmente"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"10523\" class=\"elementor elementor-10523\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0b48297 e-flex e-con-boxed e-con e-parent\" data-id=\"0b48297\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7f600fa elementor-widget elementor-widget-text-editor\" data-id=\"7f600fa\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Em 9 de outubro, a Geely Auto anunciou oficialmente que o Geely Xingyuan foi oficialmente lan\u00e7ado no mercado. O Geely Xingyuan oferece 7 op\u00e7\u00f5es de pintura externa e est\u00e1 posicionado como um sed\u00e3 compacto puramente el\u00e9trico. Ele tem alcances CLTC puramente el\u00e9tricos de 310 quil\u00f4metros e 410 quil\u00f4metros.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f8601d elementor-widget elementor-widget-image\" data-id=\"7f8601d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2508\" height=\"1672\" src=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/bf6170b24cd645aeb440a474dd04d18fnoop.webp\" class=\"attachment-full size-full wp-image-10530\" alt=\"\" srcset=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/bf6170b24cd645aeb440a474dd04d18fnoop.webp 2508w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/bf6170b24cd645aeb440a474dd04d18fnoop-300x200.webp 300w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/bf6170b24cd645aeb440a474dd04d18fnoop-1024x683.webp 1024w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/bf6170b24cd645aeb440a474dd04d18fnoop-768x512.webp 768w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/bf6170b24cd645aeb440a474dd04d18fnoop-1536x1024.webp 1536w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/bf6170b24cd645aeb440a474dd04d18fnoop-2048x1365.webp 2048w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/bf6170b24cd645aeb440a474dd04d18fnoop-18x12.webp 18w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/bf6170b24cd645aeb440a474dd04d18fnoop-1200x800.webp 1200w\" sizes=\"(max-width: 2508px) 100vw, 2508px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ad9137 elementor-widget elementor-widget-image\" data-id=\"5ad9137\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2508\" height=\"1672\" src=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/89227fd20d56454485e816d32d6a5e14noop.webp\" class=\"attachment-full size-full wp-image-10531\" alt=\"\" srcset=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/89227fd20d56454485e816d32d6a5e14noop.webp 2508w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/89227fd20d56454485e816d32d6a5e14noop-300x200.webp 300w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/89227fd20d56454485e816d32d6a5e14noop-1024x683.webp 1024w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/89227fd20d56454485e816d32d6a5e14noop-768x512.webp 768w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/89227fd20d56454485e816d32d6a5e14noop-1536x1024.webp 1536w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/89227fd20d56454485e816d32d6a5e14noop-2048x1365.webp 2048w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/89227fd20d56454485e816d32d6a5e14noop-18x12.webp 18w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/89227fd20d56454485e816d32d6a5e14noop-1200x800.webp 1200w\" sizes=\"(max-width: 2508px) 100vw, 2508px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5cd4b62 elementor-widget elementor-widget-text-editor\" data-id=\"5cd4b62\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Em termos de design, o Geely Xingyuan adota um formato relativamente arredondado, com uma superf\u00edcie de carroceria relativamente lisa, ma\u00e7anetas semi-ocultas e um formato frontal com um \u201csorriso\u201d como conceito de design.<\/span><\/span> <span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Em termos de configura\u00e7\u00e3o espec\u00edfica, o Geely Xingyuan 310km Youth Edition (modelo b\u00e1sico) vem de f\u00e1brica com rodas de a\u00e7o de 15 polegadas, radar de estacionamento traseiro, imagem de r\u00e9, far\u00f3is de halog\u00eanio e outras configura\u00e7\u00f5es.<\/span><\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-828e2a6 elementor-widget elementor-widget-image\" data-id=\"828e2a6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2508\" height=\"1672\" src=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/73050e1c992c48c2974b8685345ff6a0noop.webp\" class=\"attachment-full size-full wp-image-10533\" alt=\"\" srcset=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/73050e1c992c48c2974b8685345ff6a0noop.webp 2508w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/73050e1c992c48c2974b8685345ff6a0noop-300x200.webp 300w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/73050e1c992c48c2974b8685345ff6a0noop-1024x683.webp 1024w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/73050e1c992c48c2974b8685345ff6a0noop-768x512.webp 768w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/73050e1c992c48c2974b8685345ff6a0noop-1536x1024.webp 1536w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/73050e1c992c48c2974b8685345ff6a0noop-2048x1365.webp 2048w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/73050e1c992c48c2974b8685345ff6a0noop-18x12.webp 18w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/73050e1c992c48c2974b8685345ff6a0noop-1200x800.webp 1200w\" sizes=\"(max-width: 2508px) 100vw, 2508px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4014fa5 elementor-widget elementor-widget-image\" data-id=\"4014fa5\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2508\" height=\"1672\" src=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/6c8276c90f9548e1a5ce990c21eaf6bfnoop.webp\" class=\"attachment-full size-full wp-image-10534\" alt=\"\" srcset=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/6c8276c90f9548e1a5ce990c21eaf6bfnoop.webp 2508w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/6c8276c90f9548e1a5ce990c21eaf6bfnoop-300x200.webp 300w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/6c8276c90f9548e1a5ce990c21eaf6bfnoop-1024x683.webp 1024w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/6c8276c90f9548e1a5ce990c21eaf6bfnoop-768x512.webp 768w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/6c8276c90f9548e1a5ce990c21eaf6bfnoop-1536x1024.webp 1536w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/6c8276c90f9548e1a5ce990c21eaf6bfnoop-2048x1365.webp 2048w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/6c8276c90f9548e1a5ce990c21eaf6bfnoop-18x12.webp 18w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/6c8276c90f9548e1a5ce990c21eaf6bfnoop-1200x800.webp 1200w\" sizes=\"(max-width: 2508px) 100vw, 2508px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ad7990 elementor-widget elementor-widget-image\" data-id=\"1ad7990\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2508\" height=\"1672\" src=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/bac7c9f8909245d19a6c95db0588d02enoop.webp\" class=\"attachment-full size-full wp-image-10535\" alt=\"\" srcset=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/bac7c9f8909245d19a6c95db0588d02enoop.webp 2508w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/bac7c9f8909245d19a6c95db0588d02enoop-300x200.webp 300w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/bac7c9f8909245d19a6c95db0588d02enoop-1024x683.webp 1024w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/bac7c9f8909245d19a6c95db0588d02enoop-768x512.webp 768w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/bac7c9f8909245d19a6c95db0588d02enoop-1536x1024.webp 1536w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/bac7c9f8909245d19a6c95db0588d02enoop-2048x1365.webp 2048w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/bac7c9f8909245d19a6c95db0588d02enoop-18x12.webp 18w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/bac7c9f8909245d19a6c95db0588d02enoop-1200x800.webp 1200w\" sizes=\"(max-width: 2508px) 100vw, 2508px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-005d4c0 elementor-widget elementor-widget-image\" data-id=\"005d4c0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2508\" height=\"1672\" src=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/3fb2fce78bc24ea0a0cba0d4b12fb460noop.webp\" class=\"attachment-full size-full wp-image-10536\" alt=\"\" srcset=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/3fb2fce78bc24ea0a0cba0d4b12fb460noop.webp 2508w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/3fb2fce78bc24ea0a0cba0d4b12fb460noop-300x200.webp 300w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/3fb2fce78bc24ea0a0cba0d4b12fb460noop-1024x683.webp 1024w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/3fb2fce78bc24ea0a0cba0d4b12fb460noop-768x512.webp 768w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/3fb2fce78bc24ea0a0cba0d4b12fb460noop-1536x1024.webp 1536w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/3fb2fce78bc24ea0a0cba0d4b12fb460noop-2048x1365.webp 2048w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/3fb2fce78bc24ea0a0cba0d4b12fb460noop-18x12.webp 18w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/3fb2fce78bc24ea0a0cba0d4b12fb460noop-1200x800.webp 1200w\" sizes=\"(max-width: 2508px) 100vw, 2508px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f78fcb1 elementor-widget elementor-widget-text-editor\" data-id=\"f78fcb1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Os modelos Geely Star Wish de m\u00e9dio e alto padr\u00e3o s\u00e3o equipados com rodas de liga de alum\u00ednio de 16 polegadas, far\u00f3is de LED autom\u00e1ticos, espelhos retrovisores externos aquecidos eletricamente, etc. O modelo topo de linha (Star Wish UP 410km Exploration+ Edition) \u00e9 equipado com uma porta traseira el\u00e9trica.<\/span><\/span> <span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">O novo carro est\u00e1 dispon\u00edvel em 7 cores externas: arroz baunilha, verde manjeric\u00e3o, rosa gelo, branco leite, prata mousse, cinza trufa e azul sal marinho.<\/span><\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07b1125 elementor-widget elementor-widget-image\" data-id=\"07b1125\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2508\" height=\"1672\" src=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/208f89bb99c04f0cb9a7a871030c5e1fnoop.webp\" class=\"attachment-full size-full wp-image-10537\" alt=\"\" srcset=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/208f89bb99c04f0cb9a7a871030c5e1fnoop.webp 2508w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/208f89bb99c04f0cb9a7a871030c5e1fnoop-300x200.webp 300w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/208f89bb99c04f0cb9a7a871030c5e1fnoop-1024x683.webp 1024w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/208f89bb99c04f0cb9a7a871030c5e1fnoop-768x512.webp 768w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/208f89bb99c04f0cb9a7a871030c5e1fnoop-1536x1024.webp 1536w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/208f89bb99c04f0cb9a7a871030c5e1fnoop-2048x1365.webp 2048w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/208f89bb99c04f0cb9a7a871030c5e1fnoop-18x12.webp 18w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/208f89bb99c04f0cb9a7a871030c5e1fnoop-1200x800.webp 1200w\" sizes=\"(max-width: 2508px) 100vw, 2508px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f6f536 elementor-widget elementor-widget-image\" data-id=\"4f6f536\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2508\" height=\"1672\" src=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/0af822f7537148d6a9adedf4040091f1noop.webp\" class=\"attachment-full size-full wp-image-10538\" alt=\"\" srcset=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/0af822f7537148d6a9adedf4040091f1noop.webp 2508w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/0af822f7537148d6a9adedf4040091f1noop-300x200.webp 300w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/0af822f7537148d6a9adedf4040091f1noop-1024x683.webp 1024w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/0af822f7537148d6a9adedf4040091f1noop-768x512.webp 768w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/0af822f7537148d6a9adedf4040091f1noop-1536x1024.webp 1536w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/0af822f7537148d6a9adedf4040091f1noop-2048x1365.webp 2048w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/0af822f7537148d6a9adedf4040091f1noop-18x12.webp 18w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/0af822f7537148d6a9adedf4040091f1noop-1200x800.webp 1200w\" sizes=\"(max-width: 2508px) 100vw, 2508px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8eaeefe elementor-widget elementor-widget-text-editor\" data-id=\"8eaeefe\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Em termos de tamanho da carroceria, o comprimento, largura e altura do Geely Xingyuan s\u00e3o 4135\/1805\/1570 mm, respectivamente, com uma dist\u00e2ncia entre eixos de 2650 mm. Ele tem um layout de 5 assentos dentro do carro e \u00e9 posicionado como um carro compacto el\u00e9trico. Modelos do mesmo n\u00edvel podem incluir BYD Dolphin, Ora Good Cat, etc.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-79ee0bf elementor-widget elementor-widget-image\" data-id=\"79ee0bf\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1620\" height=\"1080\" src=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/134214e6d78141dabe514a901706045bnoop.webp\" class=\"attachment-full size-full wp-image-10539\" alt=\"\" srcset=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/134214e6d78141dabe514a901706045bnoop.webp 1620w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/134214e6d78141dabe514a901706045bnoop-300x200.webp 300w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/134214e6d78141dabe514a901706045bnoop-1024x683.webp 1024w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/134214e6d78141dabe514a901706045bnoop-768x512.webp 768w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/134214e6d78141dabe514a901706045bnoop-1536x1024.webp 1536w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/134214e6d78141dabe514a901706045bnoop-18x12.webp 18w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/134214e6d78141dabe514a901706045bnoop-1200x800.webp 1200w\" sizes=\"(max-width: 1620px) 100vw, 1620px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c7f834 elementor-widget elementor-widget-image\" data-id=\"2c7f834\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2508\" height=\"1672\" src=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/94b7a6e63e194aa7a310390ba086bd9bnoop.webp\" class=\"attachment-full size-full wp-image-10540\" alt=\"\" srcset=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/94b7a6e63e194aa7a310390ba086bd9bnoop.webp 2508w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/94b7a6e63e194aa7a310390ba086bd9bnoop-300x200.webp 300w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/94b7a6e63e194aa7a310390ba086bd9bnoop-1024x683.webp 1024w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/94b7a6e63e194aa7a310390ba086bd9bnoop-768x512.webp 768w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/94b7a6e63e194aa7a310390ba086bd9bnoop-1536x1024.webp 1536w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/94b7a6e63e194aa7a310390ba086bd9bnoop-2048x1365.webp 2048w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/94b7a6e63e194aa7a310390ba086bd9bnoop-18x12.webp 18w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/94b7a6e63e194aa7a310390ba086bd9bnoop-1200x800.webp 1200w\" sizes=\"(max-width: 2508px) 100vw, 2508px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9577409 elementor-widget elementor-widget-text-editor\" data-id=\"9577409\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Em termos de interior, o Geely Xingyuan adota um estilo de layout de cabine sim\u00e9trico, fornecendo um painel de instrumentos LCD de 8,8 polegadas, uma tela sens\u00edvel ao toque central de 14,6 polegadas (resolu\u00e7\u00e3o de 1920\u00d71080 pixels, taxa de atualiza\u00e7\u00e3o de 60 Hz), um volante multifuncional de raios duplos de fundo plano, etc. A posi\u00e7\u00e3o do passageiro no console central e o revestimento da porta s\u00e3o decorados com gr\u00e1ficos de edif\u00edcios urbanos.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58076ab elementor-widget elementor-widget-image\" data-id=\"58076ab\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1620\" height=\"1080\" src=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/b307dd26fb3e49539b0c7ea10b70f9canoop.webp\" class=\"attachment-full size-full wp-image-10542\" alt=\"\" srcset=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/b307dd26fb3e49539b0c7ea10b70f9canoop.webp 1620w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/b307dd26fb3e49539b0c7ea10b70f9canoop-300x200.webp 300w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/b307dd26fb3e49539b0c7ea10b70f9canoop-1024x683.webp 1024w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/b307dd26fb3e49539b0c7ea10b70f9canoop-768x512.webp 768w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/b307dd26fb3e49539b0c7ea10b70f9canoop-1536x1024.webp 1536w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/b307dd26fb3e49539b0c7ea10b70f9canoop-18x12.webp 18w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/b307dd26fb3e49539b0c7ea10b70f9canoop-1200x800.webp 1200w\" sizes=\"(max-width: 1620px) 100vw, 1620px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4fc66c0 elementor-widget elementor-widget-text-editor\" data-id=\"4fc66c0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"AxqVh\"><div class=\"OPPzxe\"><div class=\"QcsUad BDJ8fb BLojaf sMVRZe hCXDsb wneUed\"><div class=\"usGWQd\"><div class=\"KkbLmb\"><div class=\"lRu31\" dir=\"ltr\"><span class=\"HwtZe\" lang=\"en\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">A Geely Xingyuan oferece duas cores de cabine: Sky Mirror White e Fairy Green. A tela de controle central \u00e9 combinada com o sistema de carro Flyme Auto, que suporta troca de papel de parede na \u00e1rea de trabalho, cart\u00f5es r\u00e1pidos, personaliza\u00e7\u00e3o da fun\u00e7\u00e3o da barra de navega\u00e7\u00e3o, interconex\u00e3o de carro Flyme Link, vers\u00e3o personalizada do mapa AutoNavi, intera\u00e7\u00e3o de voz de zona dupla, imagem panor\u00e2mica de 540 graus, etc. O carro tamb\u00e9m \u00e9 equipado com \u00e1udio externo de IA e modos de cena, como espa\u00e7o de descanso e modo de acampamento.<\/span><\/span><\/span><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8b47d94 elementor-widget elementor-widget-image\" data-id=\"8b47d94\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2508\" height=\"1672\" src=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/3c5c0911b08a4295846b5f2af501b24bnoop.webp\" class=\"attachment-full size-full wp-image-10541\" alt=\"\" srcset=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/3c5c0911b08a4295846b5f2af501b24bnoop.webp 2508w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/3c5c0911b08a4295846b5f2af501b24bnoop-300x200.webp 300w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/3c5c0911b08a4295846b5f2af501b24bnoop-1024x683.webp 1024w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/3c5c0911b08a4295846b5f2af501b24bnoop-768x512.webp 768w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/3c5c0911b08a4295846b5f2af501b24bnoop-1536x1024.webp 1536w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/3c5c0911b08a4295846b5f2af501b24bnoop-2048x1365.webp 2048w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/3c5c0911b08a4295846b5f2af501b24bnoop-18x12.webp 18w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/3c5c0911b08a4295846b5f2af501b24bnoop-1200x800.webp 1200w\" sizes=\"(max-width: 2508px) 100vw, 2508px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7233a14 elementor-widget elementor-widget-image\" data-id=\"7233a14\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1620\" height=\"1080\" src=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/7999f0a231844ed2b543e1eb07e9b01anoop.webp\" class=\"attachment-full size-full wp-image-10543\" alt=\"\" srcset=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/7999f0a231844ed2b543e1eb07e9b01anoop.webp 1620w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/7999f0a231844ed2b543e1eb07e9b01anoop-300x200.webp 300w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/7999f0a231844ed2b543e1eb07e9b01anoop-1024x683.webp 1024w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/7999f0a231844ed2b543e1eb07e9b01anoop-768x512.webp 768w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/7999f0a231844ed2b543e1eb07e9b01anoop-1536x1024.webp 1536w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/7999f0a231844ed2b543e1eb07e9b01anoop-18x12.webp 18w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/7999f0a231844ed2b543e1eb07e9b01anoop-1200x800.webp 1200w\" sizes=\"(max-width: 1620px) 100vw, 1620px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba251d5 elementor-widget elementor-widget-text-editor\" data-id=\"ba251d5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>O Star Wish 310km Youth Edition (modelo b\u00e1sico) \u00e9 equipado com airbags dianteiros para passageiro\/laterais dianteiros, freios ativos, volante multifuncional de couro, painel de instrumentos LCD de 8,8 polegadas, tela sens\u00edvel ao toque central de 10,1 polegadas (sistema automotivo Galaxy Flyme Auto), mapeamento de interconex\u00e3o de celular, bancos de couro sint\u00e9tico (ajuste manual do passageiro dianteiro), ar condicionado autom\u00e1tico, controle remoto por aplicativo de celular, 4 alto-falantes, ponto de acesso Wi-Fi, etc. Com base nisso, o Star Wish 310km Dream Edition \u00e9 principalmente atualizado\/adicionado com rodas de liga de alum\u00ednio de 16 polegadas, controle de cruzeiro, tela sens\u00edvel ao toque central de 14,6 polegadas, porta de carregamento USB traseira, far\u00f3is de LED autom\u00e1ticos, espelhos retrovisores externos aquecidos eletricamente, etc.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ca1274 elementor-widget elementor-widget-image\" data-id=\"9ca1274\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1620\" height=\"1080\" src=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/7eaa95abd8c6456b862e1295b227e672noop.webp\" class=\"attachment-full size-full wp-image-10544\" alt=\"\" srcset=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/7eaa95abd8c6456b862e1295b227e672noop.webp 1620w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/7eaa95abd8c6456b862e1295b227e672noop-300x200.webp 300w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/7eaa95abd8c6456b862e1295b227e672noop-1024x683.webp 1024w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/7eaa95abd8c6456b862e1295b227e672noop-768x512.webp 768w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/7eaa95abd8c6456b862e1295b227e672noop-1536x1024.webp 1536w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/7eaa95abd8c6456b862e1295b227e672noop-18x12.webp 18w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/7eaa95abd8c6456b862e1295b227e672noop-1200x800.webp 1200w\" sizes=\"(max-width: 1620px) 100vw, 1620px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62b3df4 elementor-widget elementor-widget-text-editor\" data-id=\"62b3df4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">A configura\u00e7\u00e3o b\u00e1sica do Star Wish 410km Freedom Edition \u00e9 basicamente a mesma do 310km Youth Edition.<\/span><\/span> <span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Comparado com o Freedom Edition de 410 km, o pre\u00e7o de pr\u00e9-venda do Star Wish UP 410 km Exploration Edition \u00e9 6.000 yuans mais alto, e a configura\u00e7\u00e3o \u00e9 principalmente atualizada\/adicionada com rodas de liga de alum\u00ednio de 16 polegadas, controle de cruzeiro, tela sens\u00edvel ao toque central de 14,6 polegadas, ajuste el\u00e9trico do banco do motorista, bancos dianteiros aquecidos, porta de carregamento USB traseira, far\u00f3is de LED autom\u00e1ticos, espelhos externos aquecidos, etc.<\/span><\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d462aff elementor-widget elementor-widget-image\" data-id=\"d462aff\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1620\" height=\"1080\" src=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/503a7915e0064e9995ad10126a10c168noop.webp\" class=\"attachment-full size-full wp-image-10545\" alt=\"\" srcset=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/503a7915e0064e9995ad10126a10c168noop.webp 1620w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/503a7915e0064e9995ad10126a10c168noop-300x200.webp 300w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/503a7915e0064e9995ad10126a10c168noop-1024x683.webp 1024w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/503a7915e0064e9995ad10126a10c168noop-768x512.webp 768w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/503a7915e0064e9995ad10126a10c168noop-1536x1024.webp 1536w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/503a7915e0064e9995ad10126a10c168noop-18x12.webp 18w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/503a7915e0064e9995ad10126a10c168noop-1200x800.webp 1200w\" sizes=\"(max-width: 1620px) 100vw, 1620px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ff2b4b elementor-widget elementor-widget-text-editor\" data-id=\"8ff2b4b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Comparado com a Exploration Edition, o Star Wish UP 410km Exploration+ Edition tem grandes atualiza\u00e7\u00f5es\/adi\u00e7\u00f5es em termos de airbags laterais, imagens panor\u00e2micas de 360 graus + imagens transparentes, carregamento sem fio de celular, luzes ambiente de 256 cores, sa\u00eddas de ar-condicionado traseiras, \u00e1udio de 6 alto-falantes, etc.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c584704 elementor-widget elementor-widget-image\" data-id=\"c584704\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1620\" height=\"1080\" src=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/8ff8094a7df140d586bc902db427e11anoop.webp\" class=\"attachment-full size-full wp-image-10546\" alt=\"\" srcset=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/8ff8094a7df140d586bc902db427e11anoop.webp 1620w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/8ff8094a7df140d586bc902db427e11anoop-300x200.webp 300w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/8ff8094a7df140d586bc902db427e11anoop-1024x683.webp 1024w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/8ff8094a7df140d586bc902db427e11anoop-768x512.webp 768w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/8ff8094a7df140d586bc902db427e11anoop-1536x1024.webp 1536w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/8ff8094a7df140d586bc902db427e11anoop-18x12.webp 18w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/8ff8094a7df140d586bc902db427e11anoop-1200x800.webp 1200w\" sizes=\"(max-width: 1620px) 100vw, 1620px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5af99a5 elementor-widget elementor-widget-text-editor\" data-id=\"5af99a5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">O encosto do banco traseiro Geely Xingyuan tem um \u00e2ngulo de inclina\u00e7\u00e3o de 117 graus e \u00e9 equipado com sa\u00eddas de ar condicionado traseiras.<\/span><\/span> <span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">O porta-malas tem um volume b\u00e1sico de 375 litros, e os bancos traseiros podem ser rebatidos na propor\u00e7\u00e3o de 4\/6, e o porta-malas pode ser expandido para 1.320 litros.<\/span><\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-496fe98 elementor-widget elementor-widget-image\" data-id=\"496fe98\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2508\" height=\"1672\" src=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/187cc4b8686841619098230d517ad930noop.webp\" class=\"attachment-full size-full wp-image-10547\" alt=\"\" srcset=\"https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/187cc4b8686841619098230d517ad930noop.webp 2508w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/187cc4b8686841619098230d517ad930noop-300x200.webp 300w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/187cc4b8686841619098230d517ad930noop-1024x683.webp 1024w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/187cc4b8686841619098230d517ad930noop-768x512.webp 768w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/187cc4b8686841619098230d517ad930noop-1536x1024.webp 1536w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/187cc4b8686841619098230d517ad930noop-2048x1365.webp 2048w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/187cc4b8686841619098230d517ad930noop-18x12.webp 18w, https:\/\/www.exp-byd.com\/wp-content\/uploads\/2024\/10\/187cc4b8686841619098230d517ad930noop-1200x800.webp 1200w\" sizes=\"(max-width: 2508px) 100vw, 2508px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-89ac474 elementor-widget elementor-widget-text-editor\" data-id=\"89ac474\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Em termos de pot\u00eancia, a Geely Xingyuan fornece dois motores de pot\u00eancia. A pot\u00eancia m\u00e1xima do modelo de 310 km \u00e9 de 58 kW e o torque m\u00e1ximo \u00e9 de 130 Nm; a pot\u00eancia m\u00e1xima do modelo de 410 km \u00e9 de 85 kW e o torque m\u00e1ximo \u00e9 de 150 Nm.<\/span><\/span><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\"> O Geely Xingyuan \u00e9 equipado com baterias de fosfato de ferro-l\u00edtio fornecidas pela CATL, que t\u00eam duas vers\u00f5es de capacidade de 30,12 kWh e 40,16 kWh, correspondendo \u00e0 autonomia el\u00e9trica pura do CLTC de 310 km e 410 km.<\/span><\/span> <span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">O novo carro \u00e9 equipado com carregamento lento e carregamento r\u00e1pido como padr\u00e3o, suportando uma taxa m\u00e1xima de carregamento de 1,66C. O tempo de carregamento do 30%-80% no modo de carregamento r\u00e1pido das vers\u00f5es de 310km e 410km \u00e9 de 22,8 minutos e 24 minutos, respectivamente, suportando fun\u00e7\u00e3o de descarga externa de 3,3 kW.<\/span><\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Em 9 de outubro, a Geely Auto anunciou oficialmente que o Geely Xingyuan foi oficialmente lan\u00e7ado no mercado. O Geely Xingyuan oferece 7 op\u00e7\u00f5es de pintura externa e est\u00e1 posicionado como um sed\u00e3 compacto puramente el\u00e9trico. Ele tem alcances puramente el\u00e9tricos CLTC de 310 quil\u00f4metros e 410 quil\u00f4metros. Em termos de design, o Geely Xingyuan adota um formato relativamente arredondado, [\u2026]<\/p>","protected":false},"author":1,"featured_media":10529,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rank_math_lock_modified_date":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-10523","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-industry-news"],"_links":{"self":[{"href":"https:\/\/www.exp-byd.com\/pt\/wp-json\/wp\/v2\/posts\/10523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.exp-byd.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.exp-byd.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.exp-byd.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.exp-byd.com\/pt\/wp-json\/wp\/v2\/comments?post=10523"}],"version-history":[{"count":7,"href":"https:\/\/www.exp-byd.com\/pt\/wp-json\/wp\/v2\/posts\/10523\/revisions"}],"predecessor-version":[{"id":10550,"href":"https:\/\/www.exp-byd.com\/pt\/wp-json\/wp\/v2\/posts\/10523\/revisions\/10550"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.exp-byd.com\/pt\/wp-json\/wp\/v2\/media\/10529"}],"wp:attachment":[{"href":"https:\/\/www.exp-byd.com\/pt\/wp-json\/wp\/v2\/media?parent=10523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.exp-byd.com\/pt\/wp-json\/wp\/v2\/categories?post=10523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.exp-byd.com\/pt\/wp-json\/wp\/v2\/tags?post=10523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}